{"id":625,"date":"2026-01-08T09:33:33","date_gmt":"2026-01-08T14:33:33","guid":{"rendered":"https:\/\/jobs.concentrix.com\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/"},"modified":"2026-01-08T09:55:44","modified_gmt":"2026-01-08T14:55:44","slug":"nisreen-beraterin-fuer-inhaltsmoderation-jordanien","status":"publish","type":"game-changers","link":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/","title":{"rendered":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)"},"content":{"rendered":"\n<p>W\u00e4hrend meiner Zeit bei Concentrix habe ich meine analytischen und probleml\u00f6senden F\u00e4higkeiten gesch\u00e4rft, was mir erm\u00f6glicht, komplexe Aufgaben in der Inhaltsmoderation \u00e4u\u00dferst effizient zu bew\u00e4ltigen. Auch meine Kommunikationsf\u00e4higkeiten haben sich weiterentwickelt, sodass ich effektiver mit meinem Team zusammenarbeiten und klareres Feedback geben kann. Zudem habe ich ein scharfes Auge f\u00fcr Details entwickelt, um sicherzustellen, dass unser Inhalt den h\u00f6chsten Standards an Genauigkeit und Qualit\u00e4t entspricht.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend meiner Zeit bei Concentrix habe ich meine analytischen und probleml\u00f6senden F\u00e4higkeiten gesch\u00e4rft, was mir erm\u00f6glicht, komplexe Aufgaben in der Inhaltsmoderation \u00e4u\u00dferst effizient zu bew\u00e4ltigen. Auch meine Kommunikationsf\u00e4higkeiten haben sich weiterentwickelt, sodass ich effektiver mit meinem Team zusammenarbeiten und klareres Feedback geben kann. Zudem habe ich ein scharfes Auge f\u00fcr Details entwickelt, um sicherzustellen, dass [&hellip;]<\/p>\n","protected":false},"featured_media":622,"template":"","meta":{"_acf_changed":false},"class_list":["post-625","game-changers","type-game-changers","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien) - Concentrix Careers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)\" \/>\n<meta property=\"og:description\" content=\"W\u00e4hrend meiner Zeit bei Concentrix habe ich meine analytischen und probleml\u00f6senden F\u00e4higkeiten gesch\u00e4rft, was mir erm\u00f6glicht, komplexe Aufgaben in der Inhaltsmoderation \u00e4u\u00dferst effizient zu bew\u00e4ltigen. Auch meine Kommunikationsf\u00e4higkeiten haben sich weiterentwickelt, sodass ich effektiver mit meinem Team zusammenarbeiten und klareres Feedback geben kann. Zudem habe ich ein scharfes Auge f\u00fcr Details entwickelt, um sicherzustellen, dass [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Concentrix Careers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Concentrix-153770504699665\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T14:55:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2026\/01\/game-changer-nisreen.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@concentrix\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/\",\"url\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/\",\"name\":\"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien) - Concentrix Careers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jobs.concentrix.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/game-changer-nisreen.webp\",\"datePublished\":\"2026-01-08T14:33:33+00:00\",\"dateModified\":\"2026-01-08T14:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jobs.concentrix.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/game-changer-nisreen.webp\",\"contentUrl\":\"https:\\\/\\\/jobs.concentrix.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/game-changer-nisreen.webp\",\"width\":450,\"height\":450,\"caption\":\"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/game-changers\\\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/\",\"name\":\"Concentrix Careers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#organization\",\"name\":\"Concentrix Careers\",\"url\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jobs.concentrix.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/preview-concentrix-careers.png\",\"contentUrl\":\"https:\\\/\\\/jobs.concentrix.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/preview-concentrix-careers.png\",\"width\":960,\"height\":505,\"caption\":\"Concentrix Careers\"},\"image\":{\"@id\":\"https:\\\/\\\/jobs.concentrix.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Concentrix-153770504699665\",\"https:\\\/\\\/x.com\\\/concentrix\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien) - Concentrix Careers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/","og_locale":"de_DE","og_type":"article","og_title":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)","og_description":"W\u00e4hrend meiner Zeit bei Concentrix habe ich meine analytischen und probleml\u00f6senden F\u00e4higkeiten gesch\u00e4rft, was mir erm\u00f6glicht, komplexe Aufgaben in der Inhaltsmoderation \u00e4u\u00dferst effizient zu bew\u00e4ltigen. Auch meine Kommunikationsf\u00e4higkeiten haben sich weiterentwickelt, sodass ich effektiver mit meinem Team zusammenarbeiten und klareres Feedback geben kann. Zudem habe ich ein scharfes Auge f\u00fcr Details entwickelt, um sicherzustellen, dass [&hellip;]","og_url":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/","og_site_name":"Concentrix Careers","article_publisher":"https:\/\/www.facebook.com\/Concentrix-153770504699665","article_modified_time":"2026-01-08T14:55:44+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2026\/01\/game-changer-nisreen.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@concentrix","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/","url":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/","name":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien) - Concentrix Careers","isPartOf":{"@id":"https:\/\/jobs.concentrix.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/#primaryimage"},"image":{"@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/#primaryimage"},"thumbnailUrl":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2026\/01\/game-changer-nisreen.webp","datePublished":"2026-01-08T14:33:33+00:00","dateModified":"2026-01-08T14:55:44+00:00","breadcrumb":{"@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/#primaryimage","url":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2026\/01\/game-changer-nisreen.webp","contentUrl":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2026\/01\/game-changer-nisreen.webp","width":450,"height":450,"caption":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)"},{"@type":"BreadcrumbList","@id":"https:\/\/jobs.concentrix.com\/de\/game-changers\/nisreen-beraterin-fuer-inhaltsmoderation-jordanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jobs.concentrix.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nisreen, Beraterin f\u00fcr Inhaltsmoderation (Jordanien)"}]},{"@type":"WebSite","@id":"https:\/\/jobs.concentrix.com\/de\/#website","url":"https:\/\/jobs.concentrix.com\/de\/","name":"Concentrix Careers","description":"","publisher":{"@id":"https:\/\/jobs.concentrix.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jobs.concentrix.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jobs.concentrix.com\/de\/#organization","name":"Concentrix Careers","url":"https:\/\/jobs.concentrix.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jobs.concentrix.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2025\/11\/preview-concentrix-careers.png","contentUrl":"https:\/\/jobs.concentrix.com\/wp-content\/uploads\/2025\/11\/preview-concentrix-careers.png","width":960,"height":505,"caption":"Concentrix Careers"},"image":{"@id":"https:\/\/jobs.concentrix.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Concentrix-153770504699665","https:\/\/x.com\/concentrix"]}]}},"_links":{"self":[{"href":"https:\/\/jobs.concentrix.com\/de\/wp-json\/wp\/v2\/game-changers\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jobs.concentrix.com\/de\/wp-json\/wp\/v2\/game-changers"}],"about":[{"href":"https:\/\/jobs.concentrix.com\/de\/wp-json\/wp\/v2\/types\/game-changers"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jobs.concentrix.com\/de\/wp-json\/wp\/v2\/media\/622"}],"wp:attachment":[{"href":"https:\/\/jobs.concentrix.com\/de\/wp-json\/wp\/v2\/media?parent=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}